{"id":666,"date":"2020-01-13T21:02:34","date_gmt":"2020-01-13T21:02:34","guid":{"rendered":"http:\/\/akira.krakanan.ch\/?p=666"},"modified":"2020-01-13T21:02:34","modified_gmt":"2020-01-13T21:02:34","slug":"wjc-2020-in-trinec","status":"publish","type":"post","link":"https:\/\/akira.krakanan.ch\/en\/2020\/01\/13\/wjc-2020-in-trinec\/","title":{"rendered":"WJC 2020 in Tr\u00ecnec"},"content":{"rendered":"<p>Trotz langer Verletzungspause und kurzfristiger Grippe, konnte ich auch dieses Jahr mit der U20 Nationalmannschaft an der 2020 IIHF World Junior Championship in Ostrava &amp; Trinec \/ CZE teilnehmen. Auch wenn es f\u00fcr mich an dieser WJC zu keinem Einsatz kam, war es auch dieses mal wieder ein Ehre und ein spezielles Erlebnis.<\/p>\n<p>https:\/\/www.iihf.com\/en\/events\/2020\/wm20<\/p>","protected":false},"excerpt":{"rendered":"<p>Trotz langer Verletzungspause und kurzfristiger Grippe, konnte ich auch dieses Jahr mit der U20 Nationalmannschaft an der 2020 IIHF World Junior Championship in Ostrava &amp; Trinec \/ CZE teilnehmen. Auch wenn es f\u00fcr mich an dieser WJC zu keinem Einsatz kam, war es auch dieses mal wieder ein Ehre und ein spezielles Erlebnis. https:\/\/www.iihf.com\/en\/events\/2020\/wm20<\/p>","protected":false},"author":1,"featured_media":667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9mXxY-aK","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":731,"url":"https:\/\/akira.krakanan.ch\/en\/2020\/08\/07\/unterstuetzung-der-sporthilfe-schweiz-mcdonalds-schweiz\/","url_meta":{"origin":666,"position":0},"title":"Unterst\u00fctzung der Sporthilfe Schweiz \/ McDonald&#8217;s Schweiz","author":"admin","date":"7. August 2020","format":false,"excerpt":"Danke an Sporthilfe Schweiz und dem Team McDonald's Langnau (meinem Sporthilfe Paten), die mich auch w\u00e4hrend diesem speziellen Jahr 2020 unterst\u00fctzen, und mich dieses mal sogar mit 10% mehr! Vielen, vielen Dank daf\u00fcr! Flyer Sporthilfe McDonald's Schweiz Engagement \u00a0","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/akira.krakanan.ch\/en\/category\/news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2017\/11\/PPR_NCK2873.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2017\/11\/PPR_NCK2873.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2017\/11\/PPR_NCK2873.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2017\/11\/PPR_NCK2873.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2017\/11\/PPR_NCK2873.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":669,"url":"https:\/\/akira.krakanan.ch\/en\/2020\/01\/13\/im-a-musketeer-now\/","url_meta":{"origin":666,"position":1},"title":"I&#8217;m a Musketeer now","author":"admin","date":"13. January 2020","format":false,"excerpt":"Kurz nach der WJC 2020 haben mich die Omaha Lancers zu den Sioux City Musketeers getraded....so I'm a Musketeer now! Ich danke den Omaha Lancers f\u00fcr die M\u00f6glichkeit und das Vertrauen das sie mir entgegengebracht haben und freue mich auf die neue Herausforderung bei den Sioux City Musketeers. Omaha Lancers\u2026","rel":"","context":"In &quot;Karriere&quot;","block_context":{"text":"Karriere","link":"https:\/\/akira.krakanan.ch\/en\/category\/karriere\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2020\/01\/SiouxCity_Musketeers.png?fit=250%2C250&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":797,"url":"https:\/\/akira.krakanan.ch\/en\/2021\/04\/08\/sioux-city-musketeers-my-season-highlights-2020-2021\/","url_meta":{"origin":666,"position":2},"title":"Sioux City Musketeers: My Season Highlights 2020\/2021","author":"admin","date":"8. April 2021","format":false,"excerpt":"As we are trying to squeeze into the USHL playoffs with only a few games left in the schedule. Here some of my personal highlights of the past few weeks. Check out the current standings here Goaltender of the week 18 Goaltender of the week 20 Goaltender of the week\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/akira.krakanan.ch\/en\/category\/news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2021\/04\/20-21_GOALIE_of_the_Week_WEEK_18_SCHMID__large-300x169.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":777,"url":"https:\/\/akira.krakanan.ch\/en\/2020\/12\/13\/back-in-sioux-city\/","url_meta":{"origin":666,"position":3},"title":"Back in Sioux City","author":"admin","date":"13. December 2020","format":false,"excerpt":"Wie f\u00fcr alle war dieses Jahr auch f\u00fcr mich ein sehr spezielles Jahr. Nachdem schon der letzte Saison-Start durch Schmerzen in der H\u00fcfte gebremst wurde, und ich mich dadurch weder bei den Omaha-Lancers noch an den WJC 2020 in Ostrava\/Trinec noch bei den Sioux City Musketeers nach meinen W\u00fcnschen entsprechend\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/akira.krakanan.ch\/en\/category\/news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2020\/01\/SiouxCity_Musketeers.png?fit=250%2C250&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":833,"url":"https:\/\/akira.krakanan.ch\/en\/2021\/06\/09\/3-year-entry-level-contract-ushl-goaltender-of-the-year\/","url_meta":{"origin":666,"position":4},"title":"3-Year Entry-Level Contract &#038; USHL Goaltender of the Year","author":"admin","date":"9. June 2021","format":false,"excerpt":"Einmal mehr ein riesen Dankesch\u00f6n an die Organisation der Sioux City Musketeers! Nach einer erfolgreichen letzten Saison in der USHL konnte ich nach dem Saisonende einen 3 Jahres Einsteiger Vertrag mit den New Jersey Devils abschliessen. Ich freue mich extrem auf diese Herausforderung. RELEASE: Devils Sign G Akira Schmid to\u2026","rel":"","context":"In &quot;News&quot;","block_context":{"text":"News","link":"https:\/\/akira.krakanan.ch\/en\/category\/news\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2021\/06\/contract.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2021\/06\/contract.jpeg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2021\/06\/contract.jpeg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2021\/06\/contract.jpeg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/akira.krakanan.ch\/wp-content\/uploads\/2020\/01\/wjc2020.png?fit=434%2C230&ssl=1","_links":{"self":[{"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/posts\/666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/comments?post=666"}],"version-history":[{"count":0,"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/posts\/666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/media\/667"}],"wp:attachment":[{"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/media?parent=666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/categories?post=666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/akira.krakanan.ch\/en\/wp-json\/wp\/v2\/tags?post=666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}